{"id":253,"count":1,"description":"","link":"https:\/\/1001electrodes.com\/es\/categoria-producto\/electroliseurs\/hidrolife-bionet","name":"Hidrolife Bionet\u00ae","slug":"hidrolife-bionet","taxonomy":"product_cat","parent":56,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Hidrolife Bionet\u00ae - 1001Electrodes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/1001electrodes.com\/es\/categoria-producto\/electroliseurs\/hidrolife-bionet\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Hidrolife Bionet\u00ae - 1001Electrodes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/1001electrodes.com\/es\/categoria-producto\/electroliseurs\/hidrolife-bionet\/\" \/>\n<meta property=\"og:site_name\" content=\"1001Electrodes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/categorie-produit\\\/electroliseurs\\\/hidrolife-bionet\",\"url\":\"https:\\\/\\\/1001electrodes.com\\\/categorie-produit\\\/electroliseurs\\\/hidrolife-bionet\",\"name\":\"Archives des Hidrolife Bionet\u00ae - 1001Electrodes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/categorie-produit\\\/electroliseurs\\\/hidrolife-bionet#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/categorie-produit\\\/electroliseurs\\\/hidrolife-bionet#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/1001electrodes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9lectrolyseurs\",\"item\":\"https:\\\/\\\/1001electrodes.com\\\/categorie-produit\\\/electroliseurs\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hidrolife Bionet\u00ae\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#website\",\"url\":\"https:\\\/\\\/1001electrodes.com\\\/\",\"name\":\"1001Electrodes\",\"description\":\"Donnons une seconde vie aux \u00e9lectrolyseurs et r\u00e9duisons notre empreinte \u00e9cologique en rempla\u00e7ant uniquement la pi\u00e8ce ma\u00eetresse : L\u2019\u00c9LECTRODE !\",\"publisher\":{\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/1001electrodes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#organization\",\"name\":\"1001Electrodes\",\"url\":\"https:\\\/\\\/1001electrodes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/1001electrodes.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-1001-e\u0301lectrodes.png\",\"contentUrl\":\"https:\\\/\\\/1001electrodes.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-1001-e\u0301lectrodes.png\",\"width\":2560,\"height\":302,\"caption\":\"1001Electrodes\"},\"image\":{\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Hidrolife Bionet\u00ae - 1001Electrodes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/1001electrodes.com\/es\/categoria-producto\/electroliseurs\/hidrolife-bionet\/","og_locale":"es_ES","og_type":"article","og_title":"Archives des Hidrolife Bionet\u00ae - 1001Electrodes","og_url":"https:\/\/1001electrodes.com\/es\/categoria-producto\/electroliseurs\/hidrolife-bionet\/","og_site_name":"1001Electrodes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/1001electrodes.com\/categorie-produit\/electroliseurs\/hidrolife-bionet","url":"https:\/\/1001electrodes.com\/categorie-produit\/electroliseurs\/hidrolife-bionet","name":"Archives des Hidrolife Bionet\u00ae - 1001Electrodes","isPartOf":{"@id":"https:\/\/1001electrodes.com\/#website"},"breadcrumb":{"@id":"https:\/\/1001electrodes.com\/categorie-produit\/electroliseurs\/hidrolife-bionet#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/1001electrodes.com\/categorie-produit\/electroliseurs\/hidrolife-bionet#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/1001electrodes.com\/"},{"@type":"ListItem","position":2,"name":"\u00c9lectrolyseurs","item":"https:\/\/1001electrodes.com\/categorie-produit\/electroliseurs"},{"@type":"ListItem","position":3,"name":"Hidrolife Bionet\u00ae"}]},{"@type":"WebSite","@id":"https:\/\/1001electrodes.com\/#website","url":"https:\/\/1001electrodes.com\/","name":"1001Electrodes","description":"Que demos una segunda vida a los electrolizadores y reduzcamos nuestra huella ecol\u00f3gica sustituyendo s\u00f3lo el componente clave: \u00a1EL ELECTRODO (celula) !","publisher":{"@id":"https:\/\/1001electrodes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/1001electrodes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/1001electrodes.com\/#organization","name":"1001Electrodes","url":"https:\/\/1001electrodes.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/1001electrodes.com\/#\/schema\/logo\/image\/","url":"https:\/\/1001electrodes.com\/wp-content\/uploads\/2022\/10\/logo-1001-e\u0301lectrodes.png","contentUrl":"https:\/\/1001electrodes.com\/wp-content\/uploads\/2022\/10\/logo-1001-e\u0301lectrodes.png","width":2560,"height":302,"caption":"1001Electrodes"},"image":{"@id":"https:\/\/1001electrodes.com\/#\/schema\/logo\/image\/"}}]}},"cat_url":"https:\/\/1001electrodes.com\/es\/categoria-producto\/electroliseurs\/hidrolife-bionet","_links":{"self":[{"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/product_cat\/253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/product_cat\/56"}],"wp:post_type":[{"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/product?product_cat=253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}