{"id":2632,"date":"2022-12-02T10:28:07","date_gmt":"2022-12-02T10:28:07","guid":{"rendered":"https:\/\/1001electrodes.com\/?page_id=2632"},"modified":"2023-04-20T10:13:26","modified_gmt":"2023-04-20T10:13:26","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/1001electrodes.com\/es\/mentions-legales","title":{"rendered":"Notas legales"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2632\" class=\"elementor elementor-2632\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51145d2 elementor-section-full_width elementor-section-height-full elementor-section-height-default elementor-section-items-middle\" data-id=\"51145d2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2dc10eb1\" data-id=\"2dc10eb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73999a51 elementor-widget elementor-widget-heading\" data-id=\"73999a51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Notas legales<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71ab4acc elementor-widget elementor-widget-text-editor\" data-id=\"71ab4acc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tribunal de Jurisdicci\u00f3n: TOULOUSE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09fe733 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09fe733\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82d5b37\" data-id=\"82d5b37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dedee7c elementor-widget elementor-widget-text-editor\" data-id=\"dedee7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>Definiciones<\/b><\/h3>\n<p><b>Cliente :<\/b>&nbsp;cualquier profesional o persona f\u00edsica capaz en el sentido de los art\u00edculos 1123 y siguientes del C\u00f3digo Civil, o persona jur\u00eddica, que visite el Sitio objeto de las presentes condiciones generales.<br><b>Prestaciones y Servicios :<\/b>&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;pone a disposici\u00f3n de los Clientes :<\/p>\n<p><b>Contenido :<\/b>&nbsp;Todos los elementos constituyentes la informaci\u00f3n presente en el Sitio, en particular textos - im\u00e1genes - v\u00eddeos.<\/p>\n<p><b>Informaci\u00f3n del cliente :<\/b>&nbsp;En lo sucesivo, \u00abInformaci\u00f3n (s)\u00bb que corresponde a todos los datos personales que pueden estar en poder de&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;para la gesti\u00f3n de su cuenta, la gesti\u00f3n de las relaciones con los clientes y para fines anal\u00edticos y estad\u00edsticos.<\/p>\n<p><b>Usuario :<\/b>&nbsp;Internauta iniciando sesi\u00f3n, utilizando el sitio antes mencionado.<\/p>\n<p><b>Informaci\u00f3n Personal :<\/b>&nbsp;\u00abLas informaciones que permitan, en cualquiera de sus formas, directa o indirectamente, la identificaci\u00f3n de las personas f\u00edsicas a las que se aplican\u00bb (art\u00edculo 4 de la ley 78-17 de 6 de enero de 1978).<\/p>\n<p>Los t\u00e9rminos \u00abdatos de car\u00e1cter personal\u00bb, \u00abinteresado\u00bb, \u00abencargado del tratamiento\u00bb y \u00abdatos sensibles\u00bb tienen el significado definido por el Reglamento General de Protecci\u00f3n de Datos (RGPD: n&lt; 2016-679)<\/p>\n<p><\/p>\n<h3><b>1. Presentaci\u00f3n del sitio web.<\/b><\/h3>\n<p>En virtud del art\u00edculo 6 de la Ley n\u00ba 2004-575 de 21 de junio de 2004 para la confianza en la econom\u00eda digital, se precisa a los usuarios del sitio web&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;la identidad de los diferentes agentes en el marco de su realizaci\u00f3n y seguimiento:<\/p>\n<p><strong>Propietario<\/strong>&nbsp;: SASU CORELEC Capital social de 100000\u20ac N\u00famero de IVA: FR18478960297 - 9 RUE JEAN FRANCOIS ROMIEU 31600 MURET<br><strong>Responsable de la publicaci\u00f3n<\/strong>&nbsp;: CORELEC \u2013 contact@1001electrodes.com<br>El responsable de la publicaci\u00f3n es una persona f\u00edsica o jur\u00eddica.<br><strong>Webmaster<\/strong>&nbsp;: Origin Creative Agency \u2013 hello@origin-creative.fr<br><strong>Host<\/strong>&nbsp;: 1and1 \u2013 7 Place de la Gare 57200 Sarreguemines 0970 808 911<br><strong>Delegado de Protecci\u00f3n de Datos<\/strong>&nbsp;: CORELEC \u2013 contact@1001electrodes.com<\/p>\n<p><\/p>\n<h3><b>2. Condiciones generales de utilizaci\u00f3n del sitio y de los servicios propuestos.<\/b><\/h3>\n<p>El Sitio constituye una obra del esp\u00edritu protegida por las disposiciones del C\u00f3digo de la Propiedad Intelectual y de las Regulaciones Internacionales aplicables. El Cliente no podr\u00e1 de ninguna manera reutilizar, ceder o explotar por cuenta propia la totalidad o parte de los elementos o trabajos del Sitio.<\/p>\n<p>El uso del sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;implica la plena aceptaci\u00f3n de las siguientes condiciones generales de uso. Estas condiciones de uso pueden ser modificadas o completadas en cualquier momento, los usuarios del sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;se les invita, por tanto, a consultarlos regularmente.<\/p>\n<p class=\"translation-block\">Este sitio web es normalmente accesible a los usuarios en cualquier momento. No obstante, la interrupci\u00f3n por razones de mantenimiento t\u00e9cnico podr\u00e1 ser decidida por <a href=\"https:\/\/1001electrodes.com\/es\/\" target=\"_self\">https:\/\/1001electrodes.com<\/a>, que se esforzar\u00e1 por comunicar previamente a los usuarios las fechas y horas de la intervenci\u00f3n. El sitio web <a href=\"https:\/\/1001electrodes.com\/es\/\" target=\"_self\">https:\/\/1001electrodes.com<\/a> es actualizado regularmente por Corecore responsable. Del mismo modo, los avisos legales pueden ser modificados en cualquier momento: sin embargo, se imponen al usuario que es invitado a referirse a ellos con la mayor frecuencia posible para tomar conocimiento de ellos.<\/p>\n<p><\/p>\n<h3><b>3. Descripci\u00f3n de los servicios prestados.<\/b><\/h3>\n<p>Sitio web&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;tiene por objeto facilitar informaci\u00f3n sobre el conjunto de las actividades de la sociedad. Corelec se esforzar\u00e1 por facilitar en el sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;informaci\u00f3n lo m\u00e1s precisa posible. No obstante, no podr\u00e1 ser considerado responsable de los olvidos, inexactitudes y carencias en la actualizaci\u00f3n, ya sea por \u00e9l o por los terceros socios que le faciliten dicha informaci\u00f3n.<\/p>\n<p>Toda la informaci\u00f3n indicada en el sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;se dan a t\u00edtulo indicativo y pueden evolucionar. Por otra parte, las informaciones que figuran en el sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;no son exhaustivos. Est\u00e1n sujetos a cambios realizados desde su publicaci\u00f3n en l\u00ednea.<\/p>\n<p><\/p>\n<h3><b>4. Limitaciones contractuales de los datos t\u00e9cnicos.<\/b><\/h3>\n<p>El sitio utiliza la tecnolog\u00eda JavaScript. El sitio web no ser\u00e1 responsable de los da\u00f1os materiales relacionados con el uso del sitio. Adem\u00e1s, el usuario del sitio se compromete a acceder al sitio utilizando un material nuevo, que no contenga virus y con un navegador de \u00faltima generaci\u00f3n actualizado. El sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;est\u00e1 alojado en un proveedor en el territorio de la Uni\u00f3n Europea de acuerdo con las disposiciones del Reglamento General de Protecci\u00f3n de Datos (RGPD: n en 2016-679)<\/p>\n<p>El objetivo es proporcionar una prestaci\u00f3n que garantice la mejor tasa de accesibilidad. El proveedor de alojamiento garantiza la continuidad de su servicio las 24 horas del d\u00eda, todos los d\u00edas del a\u00f1o. No obstante, se reserva la posibilidad de interrumpir el servicio de alojamiento durante los per\u00edodos m\u00e1s cortos posibles, en particular con fines de mantenimiento y mejora de sus infraestructuras, de fallo de sus infraestructuras o si las Prestaciones y Servicios generan un tr\u00e1fico considerado anormal.<\/p>\n<p>Corelec y el proveedor de alojamiento no podr\u00e1n ser considerados responsables en caso de mal funcionamiento de la red Internet, de las l\u00edneas telef\u00f3nicas o del material inform\u00e1tico y de telefon\u00eda debido, en particular, a la congesti\u00f3n de la red que impide el acceso al servidor.<\/p>\n<p><\/p>\n<h3><b>5. Propiedad intelectual y falsificaci\u00f3n.<\/b><\/h3>\n<p>Corelec es propietaria de los derechos de propiedad intelectual y posee los derechos de uso de todos los elementos accesibles en el sitio web, en particular textos, im\u00e1genes, gr\u00e1ficos, logotipos, v\u00eddeos, iconos y sonidos. Queda prohibida toda reproducci\u00f3n, representaci\u00f3n, modificaci\u00f3n, publicaci\u00f3n, adaptaci\u00f3n de la totalidad o parte de los elementos del sitio, cualquiera que sea el medio o el procedimiento utilizado, salvo autorizaci\u00f3n previa por escrito de: Corelec<\/p>\n<p><span dir=\"ltr\">Las marcas citadas en este sitio (Aquajoy<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Astral<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Autochlor<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae,<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">BIO-POOL<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae,<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">&nbsp;BSV<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, BWT<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Chlormatic<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Compuchlor<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Corelec<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Hayward<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Innowater<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Justchlor<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, K-Chlor<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Monarch<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Pacific Sel<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Paramount<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Poolmaid<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Pool Pilot<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Pool Technologie<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Regul Electronique<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Sotrem<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Sterilor<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, System 7<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">, Zodiac<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); font-size: 10px; background-color: var(--ast-global-color-5);\">\u00ae<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">&nbsp;con sus peque\u00f1as R ) y seguidas por el s\u00edmbolo \u00ae, as\u00ed como las referencias e im\u00e1genes de los productos correspondientes, son propiedad exclusiva de terceros.\u00a0 Estas marcas, referencias e im\u00e1genes pertenecientes a terceros se citan \u00fanicamente para informar al p\u00fablico de la compatibilidad de nuestros materiales presentados en este sitio con los productos de dichas marcas. Su menci\u00f3n en este sitio&nbsp;<\/span><span dir=\"ltr\" style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-5);\">por lo tanto, no puede sugerir en ning\u00fan momento que exista ning\u00fan v\u00ednculo jur\u00eddico&nbsp;<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1rem; font-style: inherit; font-weight: var( --e-global-typography-text-font-weight ); background-color: var(--ast-global-color-5);\">o comercial entre terceros titulares de estas marcas y Corelec\/ BIO-UV GROUP.<\/span><br><\/p>\n<p>Cualquier explotaci\u00f3n no autorizada del sitio o de cualquiera de los elementos que contiene ser\u00e1 considerada como constitutiva de una falsificaci\u00f3n y perseguida conforme a las disposiciones de los art\u00edculos L.335-2 y siguientes del C\u00f3digo de Propiedad Intelectual.<\/p>\n<p><b style=\"font-style: inherit; font-family: var( --e-global-typography-text-font-family ), Sans-serif; color: rgb(17, 42, 57); font-size: 1.66667rem; background-color: var(--ast-global-color-5);\">6. Limitaciones de responsabilidad.<\/b><\/p>\n<p>Corelec act\u00faa como editor del sitio. Corelec es responsable de la calidad y veracidad del Contenido que publica.<\/p>\n<p>Corelec no ser\u00e1 responsable de los da\u00f1os directos e indirectos causados al material del usuario, al acceder al sitio web&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>como consecuencia de la utilizaci\u00f3n de un material que no cumpla las especificaciones indicadas en el punto 4, o de la aparici\u00f3n de un error o de una incompatibilidad.<\/p>\n<p>Corelec tampoco ser\u00e1 responsable de los da\u00f1os indirectos (por ejemplo, una p\u00e9rdida de mercado o una oportunidad) derivados del uso del sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>. Los usuarios disponen de espacios interactivos (posibilidad de hacer preguntas en el espacio de contacto). Corelec se reserva el derecho de suprimir, sin previo aviso, cualquier contenido depositado en este espacio que contravenga la legislaci\u00f3n aplicable en Francia, en particular las disposiciones relativas a la protecci\u00f3n de datos. En su caso, Corelec se reserva tambi\u00e9n la posibilidad de impugnar la responsabilidad civil y\/o penal del usuario, en particular en caso de mensajes de car\u00e1cter racista, injurioso, difamatorio o pornogr\u00e1fico, cualquiera que sea el soporte utilizado (texto, fotograf\u00eda...).<\/p>\n<p><\/p>\n<h3><b>7. Gesti\u00f3n de datos personales.<\/b><\/h3>\n<p>El Cliente est\u00e1 informado de las normativas relativas a la comunicaci\u00f3n de marketing, la Ley de 21 de junio de 2014 para la confianza en la Econom\u00eda Digital, la Ley de Inform\u00e1tica y Libertad de 06 de agosto de 2004 y el Reglamento General de Protecci\u00f3n de Datos (RGPD: n en portada 2016-679).<\/p>\n<p><\/p>\n<h3><b>7.1 Responsables de la recogida de datos personales<\/b><\/h3>\n<p>Para los Datos Personales recogidos en el marco de la creaci\u00f3n de la cuenta personal del Usuario y de su navegaci\u00f3n por el Sitio, el responsable del tratamiento de los Datos Personales es: CORELEC. Corelec, cuyo representante legal es Laurent-Emmanuel MIGEON.<\/p>\n<p>Como responsable del tratamiento de los datos que recoge, Corelec se compromete a respetar el marco de las disposiciones legales vigentes. Corresponde en particular al Cliente establecer las finalidades de sus tratamientos de datos, proporcionar a sus clientes potenciales y clientes, a partir de la recogida de sus consentimientos, informaci\u00f3n completa sobre el tratamiento de sus datos personales y mantener un registro de los tratamientos de acuerdo con la realidad. Cada vez que Corelec procesa Datos Personales,&nbsp;<span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; background-color: var(--ast-global-color-5);\">Corelec toma todas las medidas razonables para garantizar la exactitud y pertinencia de los Datos Personales para los fines para los que Corelec<\/span><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; background-color: var(--ast-global-color-5);\">&nbsp;tratados.<\/span><\/p>\n<p><\/p>\n<h3><b>7.2 Finalidad de los datos recogidos<\/b><\/h3>\n<p>Corelec puede procesar la totalidad o parte de los datos:<\/p>\n<ul>\n<li>para permitir la navegaci\u00f3n por el Sitio y la gesti\u00f3n y trazabilidad de las prestaciones y servicios encargados por el usuario: datos de conexi\u00f3n y de utilizaci\u00f3n del Sitio, facturaci\u00f3n, historial de pedidos, etc.<\/li>\n<li>para prevenir y combatir el fraude inform\u00e1tico (spamming, hacking...): material inform\u00e1tico utilizado para la navegaci\u00f3n, la direcci\u00f3n IP, la contrase\u00f1a (hash)<\/li>\n<li>para mejorar la navegaci\u00f3n en el Sitio: datos de conexi\u00f3n y de uso<\/li>\n<li>para llevar a cabo encuestas voluntarias de satisfacci\u00f3n&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;: direcci\u00f3n de correo electr\u00f3nico<\/li>\n<li>para realizar campa\u00f1as de comunicaci\u00f3n (sms, correo electr\u00f3nico): n\u00famero de tel\u00e9fono, direcci\u00f3n de correo electr\u00f3nico<\/li>\n<\/ul>\n<p>Corelec no comercializa sus datos personales, por lo que solo se utilizan por necesidad o con fines estad\u00edsticos y anal\u00edticos.<\/p>\n<p><\/p>\n<h3><b>7.3 Derecho de acceso, rectificaci\u00f3n y oposici\u00f3n<\/b><\/h3>\n<p>De acuerdo con la normativa europea vigente, los Usuarios de&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;tienen los siguientes derechos :<\/p>\n<ul>\n<li>derecho de acceso (art\u00edculo 15 del RGPD) y de rectificaci\u00f3n (art\u00edculo 16 del RGPD), de actualizaci\u00f3n, de cumplimentaci\u00f3n de los datos de los Usuarios con derecho a bloquear o borrar los datos de los Usuarios de car\u00e1cter personal (art\u00edculo 17 del RGPD), cuando sean inexactos, incompletas, equ\u00edvocas, caducadas, o cuya recogida, utilizaci\u00f3n, comunicaci\u00f3n o conservaci\u00f3n est\u00e9n prohibidas<\/li>\n<li>derecho a retirar el consentimiento en cualquier momento (art\u00edculo 13-2c RGPD)<\/li>\n<li>derecho a la limitaci\u00f3n del tratamiento de los datos de los Usuarios (art\u00edculo 18 del RGPD)<\/li>\n<li>derecho a oponerse al tratamiento de los datos de los Usuarios (art\u00edculo 21 del RGPD)<\/li>\n<li>derecho a la portabilidad de los datos que los Usuarios hayan facilitado, cuando dichos datos sean objeto de tratamientos automatizados basados en su consentimiento o en un contrato (art\u00edculo 20 del RGPD)<\/li>\n<li>derecho a definir el destino de los datos de los Usuarios despu\u00e9s de su muerte y a elegir a qui\u00e9n&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;deber\u00e1 comunicar (o no) sus datos a un tercero que haya designado previamente<\/li>\n<\/ul>\n<p>En cuanto Corelec tenga conocimiento de la muerte de un Usuario y a falta de instrucciones por su parte, Corelec se compromete a destruir sus datos, salvo que su conservaci\u00f3n sea necesaria para fines probatorios o para cumplir una obligaci\u00f3n legal.<\/p>\n<p>Si el Usuario desea saber c\u00f3mo&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;utiliza sus Datos Personales, solicita su rectificaci\u00f3n o se opone a su tratamiento, el Usuario puede ponerse en contacto con Corelec por escrito a la siguiente direcci\u00f3n:<\/p>\n<p>CORELEC \u2013 DPO, CORELEC<br>9 RUE JEAN FRANCOIS ROMIEU 31600 MURET.<\/p>\n<p>En este caso, el Usuario debe indicar los Datos Personales que desea que Corelec corrija, actualice o elimine, identific\u00e1ndose con precisi\u00f3n con una copia de un documento de identidad (documento de identidad o pasaporte).<\/p>\n<p>Las solicitudes de eliminaci\u00f3n de Datos Personales estar\u00e1n sujetas a las obligaciones impuestas a&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;por la ley, en particular en materia de conservaci\u00f3n o archivo de los documentos. Por \u00faltimo, los Usuarios de&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;pueden presentar una reclamaci\u00f3n ante las autoridades de control y, en particular, ante la CNIL (https:\/\/www.cnil.fr\/fr\/plaintes).<\/p>\n<p><\/p>\n<h3><b>7.4 No comunicaci\u00f3n de datos personales<\/b><\/h3>\n<p>Corelec no procesar\u00e1, alojar\u00e1 ni transferir\u00e1 la Informaci\u00f3n recopilada sobre sus Clientes a un pa\u00eds situado fuera de la Uni\u00f3n Europea o reconocido como \u00abno adecuado\u00bb por la Comisi\u00f3n Europea sin informar previamente al cliente. Sin embargo,&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;sigue siendo libre de elegir a sus subcontratistas t\u00e9cnicos y comerciales a condici\u00f3n de que presenten las garant\u00edas suficientes con respecto a los requisitos del Reglamento General de Protecci\u00f3n de Datos (RGPD: n\u00b3 2016-679).<\/p>\n<p>Corelec se compromete a tomar todas las precauciones necesarias para preservar la seguridad de la Informaci\u00f3n y, en particular, para que no sea comunicada a personas no autorizadas. Sin embargo, si un incidente que afecte a la integridad o confidencialidad de la Informaci\u00f3n del Cliente se pone en conocimiento de&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>deber\u00e1 informar lo antes posible al Cliente y comunicarle las medidas de correcci\u00f3n adoptadas. Por otra parte&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;no recopilar\u00e1 \u00abdatos sensibles\u00bb.<\/p>\n<p>Los Datos Personales del Usuario pueden ser tratados por filiales de Corelec y subcontratistas (proveedores de servicios), exclusivamente con el fin de lograr los fines de esta pol\u00edtica.<\/p>\n<p>Dentro de los l\u00edmites de sus atribuciones respectivas y para los fines antes mencionados, las principales personas que pueden tener acceso a los datos de los Usuarios de&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;son principalmente los agentes de nuestro servicio al cliente.<\/p>\n<p><\/p>\n<h3><b>8. Notificaci\u00f3n de incidentes<\/b><\/h3>\n<p>Independientemente de los esfuerzos realizados, ning\u00fan m\u00e9todo de transmisi\u00f3n por Internet ni ning\u00fan m\u00e9todo de almacenamiento electr\u00f3nico es completamente seguro. Por lo tanto, no podemos garantizar una seguridad absoluta. Si detectamos una brecha de seguridad, alertaremos a los usuarios afectados para que puedan tomar las medidas adecuadas. Nuestros procedimientos de notificaci\u00f3n de incidentes tienen en cuenta nuestras obligaciones legales, tanto a nivel nacional como europeo. Nos comprometemos a informar plenamente a nuestros clientes de todas las cuestiones relacionadas con la seguridad de sus cuentas y a proporcionarles toda la informaci\u00f3n necesaria para ayudarles a cumplir con sus propias obligaciones reglamentarias de informaci\u00f3n.<\/p>\n<p>Ninguna informaci\u00f3n personal del usuario del sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;no se publique sin el conocimiento del usuario, intercambiada, transferida, cedida o vendida en cualquier soporte a terceros. S\u00f3lo la hip\u00f3tesis de la compra de Corelec y de sus derechos permitir\u00eda la transmisi\u00f3n de dicha informaci\u00f3n al posible comprador, que a su vez estar\u00eda obligado a la misma obligaci\u00f3n de conservaci\u00f3n y modificaci\u00f3n de los datos frente al usuario del sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>.<\/p>\n<p><\/p>\n<h3><b>Seguridad<\/b><\/h3>\n<p>Para garantizar la seguridad y confidencialidad de los Datos Personales y de los Datos Personales de Salud,&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;utiliza redes protegidas por dispositivos est\u00e1ndar como cortafuegos, seudonimizaci\u00f3n, cifrado y contrase\u00f1a.<\/p>\n<p>Al procesar los datos personales,&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;adoptar\u00e1 todas las medidas razonables para protegerlos contra p\u00e9rdidas, uso indebido, acceso no autorizado, divulgaci\u00f3n, alteraci\u00f3n o destrucci\u00f3n.<\/p>\n<p><\/p>\n<h3><b>9. Hiperv\u00ednculos \u00abcookies\u00bb y etiquetas (\"etiquetas\") internet<\/b><\/h3>\n<p>Sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;contiene una serie de hiperv\u00ednculos a otros sitios, establecidos con el permiso de Corelec. Sin embargo, Corelec no tiene la posibilidad de verificar el contenido de los sitios web visitados, por lo que no asume ninguna responsabilidad por este hecho.<\/p>\n<p>A menos que decida deshabilitar las cookies, acepta que el sitio pueda usarlas. Puede desactivar estas cookies en cualquier momento y de forma gratuita desde las opciones de desactivaci\u00f3n que se le ofrecen y se le recuerdan a continuaci\u00f3n, sabiendo que esto puede reducir o impedir la accesibilidad a la totalidad o parte de los Servicios ofrecidos por el sitio.<\/p>\n<p><\/p>\n<h3><b>9.1. \u00ab COOKIES \u00bb<\/b><\/h3>\n<p>Una \u00abcookie\u00bb es un peque\u00f1o archivo de informaci\u00f3n enviado al navegador del Usuario y almacenado en el terminal del Usuario (por ejemplo, ordenador, smartphone) (en lo sucesivo, \u00abCookies\u00bb). Este archivo incluye informaci\u00f3n como el nombre de dominio del Usuario, el proveedor de Internet del Usuario, el sistema operativo del Usuario, as\u00ed como la fecha y hora de acceso. Las cookies no pueden da\u00f1ar el terminal del usuario.<\/p>\n<p>Corelec puede tratar la informaci\u00f3n del Usuario sobre su visita al Sitio, como las p\u00e1ginas visitadas, las b\u00fasquedas realizadas. Esta informaci\u00f3n permitir\u00e1 a&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;mejorar el contenido del Sitio, de la navegaci\u00f3n del Usuario.<\/p>\n<p>Las Cookies facilitan la navegaci\u00f3n y\/o la prestaci\u00f3n de los servicios ofrecidos por el Sitio, el Usuario puede configurar su navegador para que le permita decidir si desea o no aceptarlas de manera que las Cookies se guarden en el terminal o, al contrario, que sean rechazados, ya sea sistem\u00e1ticamente o seg\u00fan su emisor. El Usuario tambi\u00e9n puede configurar su software de navegaci\u00f3n de manera que la aceptaci\u00f3n o el rechazo de las Cookies se le ofrezcan puntualmente, antes de que una Cookie pueda ser registrada en su terminal.&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;informa al Usuario de que, en este caso, puede que no todas las funcionalidades de su programa de navegaci\u00f3n est\u00e9n disponibles.<\/p>\n<p>Si el Usuario rechaza el almacenamiento de Cookies en su dispositivo o navegador, o si el Usuario elimina los almacenados en \u00e9l, el Usuario es informado de que su navegaci\u00f3n y experiencia en el Sitio pueden ser limitadas. Tambi\u00e9n podr\u00eda ser el caso cuando Corelec uno de sus proveedores no pueda reconocer, a efectos de compatibilidad t\u00e9cnica, el tipo de navegador utilizado por el terminal, la configuraci\u00f3n de idioma y visualizaci\u00f3n o el pa\u00eds desde el que el dispositivo parece estar conectado a Internet.<\/p>\n<p class=\"translation-block\">En su caso, Corelec declina toda responsabilidad por las consecuencias vinculadas al funcionamiento degradado del Sitio y de los servicios eventualmente propuestos por <a href=\"https:\/\/1001electrodes.com\/es\/\" target=\"_self\">https:\/1001electrodes.com<\/a>, \n resultante (i) el rechazo de Cookies por el Usuario (ii) de la imposibilidad para <a href=\"https:\/\/1001electrodes.com\/es\/\" target=\"_self\">https:\/\/1001electrodes.com<\/a> de registrar o consultar las Cookies necesarias para su funcionamiento de la elecci\u00f3n del Usuario. Para la gesti\u00f3n de las Cookies y las opciones del Usuario, la configuraci\u00f3n de cada navegador es diferente. Se describe en el men\u00fa de ayuda del navegador, que permitir\u00e1 saber c\u00f3mo el Usuario puede modificar sus deseos en materia de Cookies.<\/p>\n<p>En cualquier momento, el Usuario puede optar por expresar y modificar sus deseos en materia de Cookies.&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;podr\u00e1 adem\u00e1s recurrir a los servicios de proveedores externos para ayudarle a recopilar y tratar las informaciones descritas en esta secci\u00f3n.<\/p>\n<p>Por \u00faltimo, haciendo clic en los iconos dedicados a las redes sociales Twitter, Facebook, Linkedin y Google Plus que figuran en el Sitio de&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;o en su aplicaci\u00f3n m\u00f3vil y si el Usuario ha aceptado el dep\u00f3sito de cookies continuando su navegaci\u00f3n por el Sitio web o la aplicaci\u00f3n m\u00f3vil de&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>, Twitter, Facebook, Linkedin y Google Plus tambi\u00e9n pueden depositar cookies en sus dispositivos (ordenador, tablet, tel\u00e9fono m\u00f3vil).<\/p>\n<p>Estos tipos de cookies solo se almacenan en sus terminales si usted lo consiente, continuando su navegaci\u00f3n por el Sitio web o la aplicaci\u00f3n m\u00f3vil de&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>. No obstante, en cualquier momento el Usuario podr\u00e1 revocar su consentimiento a que&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;Deja ese tipo de galletas.<\/p>\n<p><\/p>\n<h3><b>Art\u00edculo 9.2. ETIQUETAS (\"ETIQUETAS\") INTERNET<\/b><\/h3>\n<p><a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;puede utilizar ocasionalmente balizas web (tambi\u00e9n llamadas \u00abetiquetas\u00bb, o balizas de acci\u00f3n, GIF de p\u00edxel \u00fanico, GIF transparentes, GIF invisibles y GIF uno por uno) e implementarlas a trav\u00e9s de un socio de an\u00e1lisis web que puede encontrarse (y por lo tanto almacenar la informaci\u00f3n correspondiente, incluida la direcci\u00f3n IP del Usuario) en un pa\u00eds extranjero.<\/p>\n<p>Estas etiquetas se colocan tanto en los anuncios en l\u00ednea que permiten a los usuarios acceder al Sitio, como en las diferentes p\u00e1ginas del mismo.<\/p>\n<p>Esta tecnolog\u00eda permite a&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;evaluar las respuestas de los visitantes al Sitio y la eficacia de sus acciones (por ejemplo, el n\u00famero de veces que se abre una p\u00e1gina y la informaci\u00f3n consultada), as\u00ed como el uso de este Sitio por el Usuario.<\/p>\n<p>El proveedor externo podr\u00e1, eventualmente, recopilar informaci\u00f3n sobre los visitantes del Sitio y de otros sitios web a trav\u00e9s de estas etiquetas, elaborar informes sobre la actividad del Sitio a la atenci\u00f3n de Corelec y prestar otros servicios relativos a la utilizaci\u00f3n del mismoci y de Internet.<\/p>\n<p><\/p>\n<h3><b>10. Derecho aplicable y atribuci\u00f3n de jurisdicci\u00f3n.<\/b><\/h3>\n<p>Cualquier disputa relacionada con el uso del sitio&nbsp;<a href=\"https:\/\/1001electrodes.com\/es\/\">https:\/\/1001electrodes.com<\/a>&nbsp;est\u00e1 sujeto al Derecho franc\u00e9s. Fuera de los casos en que la ley no lo permite, se hace atribuci\u00f3n exclusiva de jurisdicci\u00f3n a los tribunales competentes de ToulouseC<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mentions l\u00e9gales Tribunal de juridiction : TOULOUSE D\u00e9finitions Client :&nbsp;tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales.Prestations et Services :&nbsp;https:\/\/1001electrodes.com&nbsp;met \u00e0 disposition des Clients : Contenu :&nbsp;Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur le Site, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2632","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mentions L\u00e9gales - 1001Electrodes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/1001electrodes.com\/es\/mentions-legales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentions L\u00e9gales - 1001Electrodes\" \/>\n<meta property=\"og:description\" content=\"Mentions l\u00e9gales Tribunal de juridiction : TOULOUSE D\u00e9finitions Client :&nbsp;tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales.Prestations et Services :&nbsp;https:\/\/1001electrodes.com&nbsp;met \u00e0 disposition des Clients : Contenu :&nbsp;Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur le Site, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/1001electrodes.com\/es\/mentions-legales\/\" \/>\n<meta property=\"og:site_name\" content=\"1001Electrodes\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-20T10:13:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/mentions-legales\",\"url\":\"https:\\\/\\\/1001electrodes.com\\\/mentions-legales\",\"name\":\"Mentions L\u00e9gales - 1001Electrodes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#website\"},\"datePublished\":\"2022-12-02T10:28:07+00:00\",\"dateModified\":\"2023-04-20T10:13:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/mentions-legales#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/1001electrodes.com\\\/mentions-legales\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/mentions-legales#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/1001electrodes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentions L\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#website\",\"url\":\"https:\\\/\\\/1001electrodes.com\\\/\",\"name\":\"1001Electrodes\",\"description\":\"Donnons une seconde vie aux \u00e9lectrolyseurs et r\u00e9duisons notre empreinte \u00e9cologique en rempla\u00e7ant uniquement la pi\u00e8ce ma\u00eetresse : L\u2019\u00c9LECTRODE !\",\"publisher\":{\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/1001electrodes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#organization\",\"name\":\"1001Electrodes\",\"url\":\"https:\\\/\\\/1001electrodes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/1001electrodes.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-1001-e\u0301lectrodes.png\",\"contentUrl\":\"https:\\\/\\\/1001electrodes.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-1001-e\u0301lectrodes.png\",\"width\":2560,\"height\":302,\"caption\":\"1001Electrodes\"},\"image\":{\"@id\":\"https:\\\/\\\/1001electrodes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mentions L\u00e9gales - 1001Electrodes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/1001electrodes.com\/es\/mentions-legales\/","og_locale":"es_ES","og_type":"article","og_title":"Mentions L\u00e9gales - 1001Electrodes","og_description":"Mentions l\u00e9gales Tribunal de juridiction : TOULOUSE D\u00e9finitions Client :&nbsp;tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales.Prestations et Services :&nbsp;https:\/\/1001electrodes.com&nbsp;met \u00e0 disposition des Clients : Contenu :&nbsp;Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur le Site, [&hellip;]","og_url":"https:\/\/1001electrodes.com\/es\/mentions-legales\/","og_site_name":"1001Electrodes","article_modified_time":"2023-04-20T10:13:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/1001electrodes.com\/mentions-legales","url":"https:\/\/1001electrodes.com\/mentions-legales","name":"Mentions L\u00e9gales - 1001Electrodes","isPartOf":{"@id":"https:\/\/1001electrodes.com\/#website"},"datePublished":"2022-12-02T10:28:07+00:00","dateModified":"2023-04-20T10:13:26+00:00","breadcrumb":{"@id":"https:\/\/1001electrodes.com\/mentions-legales#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/1001electrodes.com\/mentions-legales"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/1001electrodes.com\/mentions-legales#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/1001electrodes.com\/"},{"@type":"ListItem","position":2,"name":"Mentions L\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/1001electrodes.com\/#website","url":"https:\/\/1001electrodes.com\/","name":"1001Electrodes","description":"Que demos una segunda vida a los electrolizadores y reduzcamos nuestra huella ecol\u00f3gica sustituyendo s\u00f3lo el componente clave: \u00a1EL ELECTRODO (celula) !","publisher":{"@id":"https:\/\/1001electrodes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/1001electrodes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/1001electrodes.com\/#organization","name":"1001Electrodes","url":"https:\/\/1001electrodes.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/1001electrodes.com\/#\/schema\/logo\/image\/","url":"https:\/\/1001electrodes.com\/wp-content\/uploads\/2022\/10\/logo-1001-e\u0301lectrodes.png","contentUrl":"https:\/\/1001electrodes.com\/wp-content\/uploads\/2022\/10\/logo-1001-e\u0301lectrodes.png","width":2560,"height":302,"caption":"1001Electrodes"},"image":{"@id":"https:\/\/1001electrodes.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/pages\/2632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/comments?post=2632"}],"version-history":[{"count":0,"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/pages\/2632\/revisions"}],"wp:attachment":[{"href":"https:\/\/1001electrodes.com\/es\/wp-json\/wp\/v2\/media?parent=2632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}